{"id":1361,"date":"2020-05-05T03:19:55","date_gmt":"2020-05-05T03:19:55","guid":{"rendered":"http:\/\/tenistenis.com\/?p=1361"},"modified":"2020-05-23T21:50:19","modified_gmt":"2020-05-23T21:50:19","slug":"las-5-grandes-de-nadal-en-madrid","status":"publish","type":"post","link":"https:\/\/tenistenis.com\/index.php\/2020\/05\/05\/las-5-grandes-de-nadal-en-madrid\/","title":{"rendered":"LAS 5 GRANDES DE NADAL EN MADRID"},"content":{"rendered":"\n<p>Durante la semana en la que deber\u00eda haberse disputado el Mutua Madrid Open, ATPTour.com hace distintos repasos a los mejores momentos del torneo. Hoy echamos un vistazo a las 5 grandes actuaciones de Rafael Nadal en la cita madrile\u00f1a.<\/p>\n\n\n\n<p><strong>2005: El Primero Ante Ljubicic<br><\/strong>El espa\u00f1ol solo hab\u00eda jugado dos veces el Mutua Madrid Open (2003 y 2004), pero esa temporada atac\u00f3 con decisi\u00f3n la victoria desde el primer momento. En el a\u00f1o de su explosi\u00f3n definitiva, meses despu\u00e9s de ganar Roland Garros con solo 18 a\u00f1os, Nadal aterriz\u00f3 en el Madrid Arena listo para intentar ganar su cuarto ATP Masters 1000. Para levantar el t\u00edtulo, Nadal dej\u00f3 por el camino a Victor Hanescu, Tommy Robredo, Radek Stepanek, Robby Ginepri e Ivan Ljubicic. Ese \u00faltimo partido sigue estando considerado como uno de los mejores en la carrera del mallorqu\u00edn: para ganar, Nadal necesit\u00f3 remontar los dos primeros sets y termin\u00f3 imponi\u00e9ndose en el tie-break de quinto por 3-6, 2-6, 6-3, 6-4, 7-6(3) en tres horas y 53 minutos de partido.<\/p>\n\n\n\n<p><strong>2009: El Partido De Los Partidos<br><\/strong>Posiblemente, el mejor partido en la historia del Mutua Madrid Open. Durante cuatro horas y 3 minutos, Nadal y Novak Djokovic firmaron una batalla impresionante que acab\u00f3 llev\u00e1ndose el espa\u00f1ol ag\u00f3nicamente porque necesit\u00f3 salvar 3 puntos de partido en el tie-break decisivo. Finalmente, el espa\u00f1ol avanz\u00f3 a la final tras imponerse en ese desempate crucial, cargado de puntos impresionantes, por 11-9. Al d\u00eda siguiente, Roger Federer venci\u00f3 a Nadal para quedarse con el primer torneo que se disput\u00f3 en la Caja M\u00e1gica.<\/p>\n\n\n\n<p><strong>2010: La Venganza<br><\/strong>Un a\u00f1o despu\u00e9s de perder la final con Federer, Nadal regres\u00f3 al partido decisivo y se llev\u00f3 el t\u00edtulo, tom\u00e1ndose su particular venganza. Al imponerse al suizo por 6-4, 7-6 (5), el espa\u00f1ol complet\u00f3 una fant\u00e1stica semana en la que dej\u00f3 fuera de combate a Alexandr Dolgopolov, John Isner, Gael Monfils, Nicol\u00e1s Almagro y al propio Federer, por aquel entonces No. 1 de la clasificaci\u00f3n.<\/p>\n\n\n\n<p><strong>2013: Un T\u00edtulo Especial<br><\/strong>Nadal ven\u00eda de un a\u00f1o complicado (2012) debido a las lesiones, que lo hab\u00edan mantenido m\u00e1s de seis meses fuera de la competici\u00f3n. Sin embargo, el a\u00f1o termin\u00f3 de destaparse en la Caja M\u00e1gica, donde consigui\u00f3 su tercer Mutua Madrid Open. Derrotando a Benoit Paire, Mikhail Youzhny, David Ferrer, Pablo And\u00fajar y Stan Wawrinka en la final, perdiendo solo un set por el camino (ante Ferrer en cuartos de final), Nadal se coron\u00f3 de nuevo en Madrid, reenganch\u00e1ndose a la senda de los triunfos en casa.<\/p>\n\n\n\n<p><strong>2017: El Quinto<br><\/strong>Esa temporada marc\u00f3 el regreso al primer plano competitivo de Nadal y Federer despu\u00e9s de varios meses apartados del circuito por distintas lesiones. Tras repartirse los t\u00edtulos en el arranque del a\u00f1o, Nadal arras\u00f3 en la gira de tierra batida europea, como en sus mejores tiempos. El Mutua Madrid Open no fue una excepci\u00f3n: el espa\u00f1ol alz\u00f3 su quinto trofeo en Madrid eliminando a Fabio Fognini, Nick Kyrgios, David Goffin, Novak Djokovic y Dominic Thiem sobre la tierra batida de la Caja M\u00e1gica.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Daily || Mutua Madrid Open: The Film\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/YoMuW1dsreA?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Durante la semana en la que deber\u00eda haberse disputado el Mutua Madrid Open, ATPTour.com hace distintos repasos a los mejores momentos del torneo. Hoy echamos un vistazo a las 5 grandes actuaciones de Rafael Nadal en la cita madrile\u00f1a. 2005: El Primero Ante LjubicicEl espa\u00f1ol solo hab\u00eda jugado dos veces el Mutua Madrid Open (2003 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":1362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[22],"class_list":{"0":"post-1361","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tenis-atp","8":"tag-tenis"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/posts\/1361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/comments?post=1361"}],"version-history":[{"count":1,"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/posts\/1361\/revisions"}],"predecessor-version":[{"id":1363,"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/posts\/1361\/revisions\/1363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/media\/1362"}],"wp:attachment":[{"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/media?parent=1361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/categories?post=1361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tenistenis.com\/index.php\/wp-json\/wp\/v2\/tags?post=1361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}